{"id":2143,"date":"2019-10-09T07:46:23","date_gmt":"2019-10-09T10:46:23","guid":{"rendered":"https:\/\/coopelcar.com.ar\/NewSite\/?p=2143"},"modified":"2019-10-09T07:46:23","modified_gmt":"2019-10-09T10:46:23","slug":"corte-de-energia-electrica-24","status":"publish","type":"post","link":"https:\/\/coopelcar.com.ar\/NewSite\/index.php\/2019\/10\/09\/corte-de-energia-electrica-24\/","title":{"rendered":"Corte de energ\u00eda el\u00e9ctrica"},"content":{"rendered":"<p>Informamos que a partir de las 8 hs y hasta las 10 hs aproximadamente se cortar\u00e1 el suministro el\u00e9ctrico desde la Ruta 158 hasta la calle Mart\u00edn Gil y desde las calles Juan Cliscagne hasta Julio Oro\u00f1o por tareas de mantenimiento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Informamos que a partir de las 8 hs y hasta las 10 hs aproximadamente se cortar\u00e1 el suministro el\u00e9ctrico desde la Ruta 158 hasta la calle Mart\u00edn Gil y desde las calles Juan Cliscagne hasta Julio Oro\u00f1o por tareas de mantenimiento.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,16],"tags":[],"class_list":["post-2143","post","type-post","status-publish","format-standard","hentry","category-aviso_rapido","category-electricidad"],"featured_image_src":"https:\/\/coopelcar.com.ar\/NewSite\/wp-includes\/images\/media\/default.svg","_links":{"self":[{"href":"https:\/\/coopelcar.com.ar\/NewSite\/index.php\/wp-json\/wp\/v2\/posts\/2143"}],"collection":[{"href":"https:\/\/coopelcar.com.ar\/NewSite\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coopelcar.com.ar\/NewSite\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coopelcar.com.ar\/NewSite\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/coopelcar.com.ar\/NewSite\/index.php\/wp-json\/wp\/v2\/comments?post=2143"}],"version-history":[{"count":1,"href":"https:\/\/coopelcar.com.ar\/NewSite\/index.php\/wp-json\/wp\/v2\/posts\/2143\/revisions"}],"predecessor-version":[{"id":2144,"href":"https:\/\/coopelcar.com.ar\/NewSite\/index.php\/wp-json\/wp\/v2\/posts\/2143\/revisions\/2144"}],"wp:attachment":[{"href":"https:\/\/coopelcar.com.ar\/NewSite\/index.php\/wp-json\/wp\/v2\/media?parent=2143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coopelcar.com.ar\/NewSite\/index.php\/wp-json\/wp\/v2\/categories?post=2143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coopelcar.com.ar\/NewSite\/index.php\/wp-json\/wp\/v2\/tags?post=2143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}